{"id":782,"date":"2025-06-08T15:55:10","date_gmt":"2025-06-08T15:55:10","guid":{"rendered":"https:\/\/m2squares.com\/?p=782"},"modified":"2025-06-08T15:55:10","modified_gmt":"2025-06-08T15:55:10","slug":"socks","status":"publish","type":"post","link":"https:\/\/m2squares.com\/index.php\/2025\/06\/08\/socks\/","title":{"rendered":"Socks"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"792\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0131-768x1024.jpg\" alt=\"\" class=\"wp-image-792\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0131-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0131-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0131-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0131-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0131-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"784\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0132-768x1024.jpg\" alt=\"\" class=\"wp-image-784\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0132-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0132-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0132-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0132-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0132-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"785\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0133-768x1024.jpg\" alt=\"\" class=\"wp-image-785\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0133-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0133-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0133-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0133-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0133-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"787\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0134-768x1024.jpg\" alt=\"\" class=\"wp-image-787\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0134-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0134-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0134-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0134-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0134-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"788\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0135-768x1024.jpg\" alt=\"\" class=\"wp-image-788\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0135-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0135-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0135-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0135-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0135-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"791\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0136-768x1024.jpg\" alt=\"\" class=\"wp-image-791\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0136-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0136-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0136-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0136-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0136-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"789\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0137-768x1024.jpg\" alt=\"\" class=\"wp-image-789\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0137-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0137-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0137-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0137-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0137-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"786\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0138-768x1024.jpg\" alt=\"\" class=\"wp-image-786\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0138-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0138-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0138-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0138-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0138-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"790\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0140-768x1024.jpg\" alt=\"\" class=\"wp-image-790\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0140-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0140-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0140-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0140-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0140-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"793\" src=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0130-768x1024.jpg\" alt=\"\" class=\"wp-image-793\" srcset=\"https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0130-768x1024.jpg 768w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0130-225x300.jpg 225w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0130-1152x1536.jpg 1152w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0130-1536x2048.jpg 1536w, https:\/\/m2squares.com\/wp-content\/uploads\/2025\/06\/IMG_0130-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":795,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions\/795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/m2squares.com\/index.php\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}